{"id":4962,"date":"2014-05-02T14:01:35","date_gmt":"2014-05-02T14:01:35","guid":{"rendered":"https:\/\/www.123fakta.com\/da\/?p=4962"},"modified":"2026-03-19T10:38:28","modified_gmt":"2026-03-19T10:38:28","slug":"datos-sobre-los-probioticos","status":"publish","type":"post","link":"https:\/\/www.123fakta.com\/es\/facts-about-probiotics","title":{"rendered":"Datos sobre los probi\u00f3ticos"},"content":{"rendered":"<ol>\n<li><strong>Definici\u00f3n:<\/strong> En 2001, la OMS defini\u00f3 <a href=\"https:\/\/www.netpatient.dk\/probiotika\">probi\u00f3ticos<\/a> como \"microorganismos vivos que, administrados en cantidades suficientes, son beneficiosos para la salud del hu\u00e9sped\". Desde entonces, se ha trabajado en la definici\u00f3n, pero sigue sin ser aceptada por la Autoridad Europea de Seguridad Alimentaria porque contiene una declaraci\u00f3n de propiedades saludables que no es mensurable.<sup><a href=\"https:\/\/en.wikipedia.org\/wiki\/Probiotic#Definition\">1<\/a><\/sup><\/li>\n<li><strong>Peso:<\/strong> El cuerpo contiene alrededor de 1,5 kilogramos de bacterias probi\u00f3ticas, que en conjunto pesan m\u00e1s que nuestro cerebro, alrededor de 1,36 kilogramos.<a href=\"https:\/\/www.medicalnewstoday.com\/articles\/324834.php\"><sup>2<\/sup><\/a><\/li>\n<li><strong>Cantidad:<\/strong> En una persona sana, hay alrededor de 100 billones (y seguramente entre un bill\u00f3n y un cuatrill\u00f3n) de microorganismos en el intestino que desempe\u00f1an un papel importante en nuestra salud. En total, hay unos 10 billones de c\u00e9lulas en el cuerpo.<sup><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3726476\/\">3<\/a><\/sup>,<sup><a href=\"https:\/\/en.wikipedia.org\/wiki\/Human_microbiota\">4<\/a><\/sup><\/li>\n<li><strong>Tribus:<\/strong> En el organismo hay m\u00e1s de 500 millones de cepas de bacterias probi\u00f3ticas. Algunas de las cepas viven all\u00ed permanentemente, mientras que otras est\u00e1n en tr\u00e1nsito. Las cepas m\u00e1s comunes son Lactobacillus, Bifidobacterium, Streptococcus y Saccharomyces boulardii. Las cepas se comportan de distintas maneras y act\u00faan de distintas formas en el organismo.<sup><a class=\"broken_link\" href=\"https:\/\/iai.asm.org\/content\/76\/8\/3360.full\">5<\/a><\/sup><\/li>\n<li><strong>Mercado:<\/strong> En 2018, el mercado mundial de alimentos y suplementos probi\u00f3ticos ascendi\u00f3 a unos 50 000 millones USD. Se espera que esta cifra aumente hasta los 70.000 millones de d\u00f3lares en 2023.<sup><a href=\"https:\/\/www.marketsandmarkets.com\/Market-Reports\/probiotic-market-advanced-technologies-and-global-market-69.html\">6<\/a><\/sup><\/li>\n<li><strong>H\u00e1bitats:<\/strong> Las bacterias probi\u00f3ticas viven en muchas partes del cuerpo, no s\u00f3lo en el intestino como podr\u00eda pensarse. Las bacterias tambi\u00e9n se encuentran en la boca, la nariz, el es\u00f3fago, el recto, las articulaciones y m\u00e1s.<\/li>\n<li><strong>Apendicitis:<\/strong> Aunque la funci\u00f3n del ap\u00e9ndice ha sido desconocida durante muchos a\u00f1os, varios estudios nuevos sugieren que puede actuar como dep\u00f3sito de bacterias probi\u00f3ticas. Entre otras cosas, los investigadores han observado que el ap\u00e9ndice se encuentra en muchos mam\u00edferos diferentes que han evolucionado en direcciones muy distintas y, sin embargo, se ha conservado en pr\u00e1cticamente todos los mam\u00edferos, incluidos los humanos. Esto puede indicar que tiene una funci\u00f3n, ya que de lo contrario deber\u00eda desaparecer con el tiempo.<sup><a href=\"https:\/\/www.sciencedaily.com\/releases\/2017\/01\/170109162333.htm\">7<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3551545\/\">8<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6023457\/\">9<\/a><\/sup><\/li>\n<li><strong>Enfermedades y dolencias<\/strong>: En los \u00faltimos a\u00f1os, se ha prestado mucha atenci\u00f3n a los probi\u00f3ticos como suplementos diet\u00e9ticos, y el consiguiente inter\u00e9s comercial por estos suplementos tambi\u00e9n ha dado lugar a una serie de afirmaciones de que pueden prevenir ciertas enfermedades. Entre ellas, el estre\u00f1imiento, los resfriados y el c\u00e1ncer. Sin embargo, cabe destacar que todas estas afirmaciones siguen siendo afirmaciones y que a\u00fan no existen pruebas cient\u00edficas de estos efectos.<sup><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4421088\/\">10<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/30248200\">11<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/23894906\">12<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/16597207\">13<\/a>,<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S2213453015000300\">14<\/a><\/sup><\/li>\n<li><strong>Sistema inmunitario:<\/strong> Se sabe que las bacterias probi\u00f3ticas influyen en el sistema inmunitario, pero se desconoce la relaci\u00f3n exacta entre ambos. Existen numerosos estudios sobre los efectos de los probi\u00f3ticos en el sistema inmunitario y muchos defensores est\u00e1n claramente convencidos de que la suplementaci\u00f3n con probi\u00f3ticos puede ayudar a mejorar la funci\u00f3n inmunitaria. Sin embargo, al igual que ocurre con las afirmaciones sobre la prevenci\u00f3n de enfermedades, los efectos beneficiosos de los suplementos probi\u00f3ticos sobre el sistema inmunitario siguen siendo afirmaciones hasta que la ciencia demuestre lo contrario.<sup><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4006993\/\">15<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/30673668\">16<\/a>,<a href=\"https:\/\/www.ora.organic\/blogs\/news\/probiotics-for-immunity-how-do-probiotics-help-the-immune-system\">17<\/a><\/sup><\/li>\n<li><strong>El nacimiento:<\/strong> Todos los beb\u00e9s nacen con un sistema intestinal est\u00e9ril, obtienen sus primeras bacterias probi\u00f3ticas a trav\u00e9s de la leche materna o de f\u00f3rmula, y m\u00e1s tarde a trav\u00e9s de los alimentos que consumen.<sup><a href=\"https:\/\/www.rch.org.au\/uploadedFiles\/Main\/Content\/ccch\/CPR_Vol22_No1_Factsheet.pdf\">18<\/a><\/sup><\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>Definici\u00f3n: En 2001, la OMS defini\u00f3 los probi\u00f3ticos como \"microorganismos vivos que, administrados en cantidades suficientes, son beneficiosos para la salud del hu\u00e9sped\". Desde entonces, se ha trabajado en la definici\u00f3n, pero sigue sin ser aceptada por la Autoridad Europea de Seguridad Alimentaria porque la definici\u00f3n contiene una declaraci\u00f3n de propiedades saludables que no es... <a title=\"Datos sobre los probi\u00f3ticos\" class=\"read-more\" href=\"https:\/\/www.123fakta.com\/es\/facts-about-probiotics\" aria-label=\"Leer m\u00e1s sobre Datos sobre los probi\u00f3ticos\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":1,"featured_media":7552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","footnotes":""},"categories":[66],"tags":[120],"class_list":["post-4962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-miscellaneous","tag-adsense"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Probiotic facts - 10 things you didn&#039;t know about probiotic bacteria<\/title>\n<meta name=\"description\" content=\"Probiotics are important. Did you know that they are stored in the appendix? Or that the body has over 500 strains of probiotic bacteria?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.123fakta.com\/es\/datos-sobre-los-probioticos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Probiotic facts - 10 things you didn&#039;t know about probiotic bacteria\" \/>\n<meta property=\"og:description\" content=\"Probiotics are important. Did you know that they are stored in the appendix? Or that the body has over 500 strains of probiotic bacteria?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.123fakta.com\/es\/datos-sobre-los-probioticos\/\" \/>\n<meta property=\"og:site_name\" content=\"123fakta.com\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-02T14:01:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T10:38:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.123fakta.com\/wp-content\/uploads\/probiotics-facts.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"782\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"The Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics\"},\"author\":{\"name\":\"The Editor\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#\\\/schema\\\/person\\\/8184fc25e34a98422f1bca2a8a55acf2\"},\"headline\":\"Facts about probiotics\",\"datePublished\":\"2014-05-02T14:01:35+00:00\",\"dateModified\":\"2026-03-19T10:38:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics\"},\"wordCount\":468,\"publisher\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.123fakta.com\\\/wp-content\\\/uploads\\\/probiotics-facts.jpg\",\"keywords\":[\"adsense\"],\"articleSection\":[\"Miscellaneous\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics\",\"url\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics\",\"name\":\"Probiotic facts - 10 things you didn't know about probiotic bacteria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.123fakta.com\\\/wp-content\\\/uploads\\\/probiotics-facts.jpg\",\"datePublished\":\"2014-05-02T14:01:35+00:00\",\"dateModified\":\"2026-03-19T10:38:28+00:00\",\"description\":\"Probiotics are important. Did you know that they are stored in the appendix? Or that the body has over 500 strains of probiotic bacteria?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics#primaryimage\",\"url\":\"https:\\\/\\\/www.123fakta.com\\\/wp-content\\\/uploads\\\/probiotics-facts.jpg\",\"contentUrl\":\"https:\\\/\\\/www.123fakta.com\\\/wp-content\\\/uploads\\\/probiotics-facts.jpg\",\"width\":1200,\"height\":782,\"caption\":\"Facts about probiotics\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/facts-about-probiotics#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.123fakta.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facts about probiotics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#website\",\"url\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/\",\"name\":\"123fakta.com\",\"description\":\"Funny, serious &amp; true facts\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#organization\",\"name\":\"123fakta.com\",\"url\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.123fakta.com\\\/wp-content\\\/uploads\\\/logo-123fakta-com.webp\",\"contentUrl\":\"https:\\\/\\\/www.123fakta.com\\\/wp-content\\\/uploads\\\/logo-123fakta-com.webp\",\"width\":300,\"height\":53,\"caption\":\"123fakta.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.123fakta.com\\\/da\\\/#\\\/schema\\\/person\\\/8184fc25e34a98422f1bca2a8a55acf2\",\"name\":\"The Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"caption\":\"The Editor\"},\"sameAs\":[\"https:\\\/\\\/www.123fakta.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datos sobre los probi\u00f3ticos - 10 cosas que no sab\u00eda sobre las bacterias probi\u00f3ticas","description":"Los probi\u00f3ticos son importantes. \u00bfSab\u00edas que se almacenan en el ap\u00e9ndice? \u00bfO que el cuerpo tiene m\u00e1s de 500 cepas de bacterias probi\u00f3ticas?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.123fakta.com\/es\/datos-sobre-los-probioticos\/","og_locale":"es_ES","og_type":"article","og_title":"Probiotic facts - 10 things you didn't know about probiotic bacteria","og_description":"Probiotics are important. Did you know that they are stored in the appendix? Or that the body has over 500 strains of probiotic bacteria?","og_url":"https:\/\/www.123fakta.com\/es\/datos-sobre-los-probioticos\/","og_site_name":"123fakta.com","article_published_time":"2014-05-02T14:01:35+00:00","article_modified_time":"2026-03-19T10:38:28+00:00","og_image":[{"width":1200,"height":782,"url":"https:\/\/www.123fakta.com\/wp-content\/uploads\/probiotics-facts.jpg","type":"image\/jpeg"}],"author":"The Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"The Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.123fakta.com\/facts-about-probiotics#article","isPartOf":{"@id":"https:\/\/www.123fakta.com\/facts-about-probiotics"},"author":{"name":"The Editor","@id":"https:\/\/www.123fakta.com\/da\/#\/schema\/person\/8184fc25e34a98422f1bca2a8a55acf2"},"headline":"Facts about probiotics","datePublished":"2014-05-02T14:01:35+00:00","dateModified":"2026-03-19T10:38:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.123fakta.com\/facts-about-probiotics"},"wordCount":468,"publisher":{"@id":"https:\/\/www.123fakta.com\/da\/#organization"},"image":{"@id":"https:\/\/www.123fakta.com\/facts-about-probiotics#primaryimage"},"thumbnailUrl":"https:\/\/www.123fakta.com\/wp-content\/uploads\/probiotics-facts.jpg","keywords":["adsense"],"articleSection":["Miscellaneous"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.123fakta.com\/facts-about-probiotics","url":"https:\/\/www.123fakta.com\/facts-about-probiotics","name":"Datos sobre los probi\u00f3ticos - 10 cosas que no sab\u00eda sobre las bacterias probi\u00f3ticas","isPartOf":{"@id":"https:\/\/www.123fakta.com\/da\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.123fakta.com\/facts-about-probiotics#primaryimage"},"image":{"@id":"https:\/\/www.123fakta.com\/facts-about-probiotics#primaryimage"},"thumbnailUrl":"https:\/\/www.123fakta.com\/wp-content\/uploads\/probiotics-facts.jpg","datePublished":"2014-05-02T14:01:35+00:00","dateModified":"2026-03-19T10:38:28+00:00","description":"Los probi\u00f3ticos son importantes. \u00bfSab\u00edas que se almacenan en el ap\u00e9ndice? \u00bfO que el cuerpo tiene m\u00e1s de 500 cepas de bacterias probi\u00f3ticas?","breadcrumb":{"@id":"https:\/\/www.123fakta.com\/facts-about-probiotics#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.123fakta.com\/facts-about-probiotics"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.123fakta.com\/facts-about-probiotics#primaryimage","url":"https:\/\/www.123fakta.com\/wp-content\/uploads\/probiotics-facts.jpg","contentUrl":"https:\/\/www.123fakta.com\/wp-content\/uploads\/probiotics-facts.jpg","width":1200,"height":782,"caption":"Facts about probiotics"},{"@type":"BreadcrumbList","@id":"https:\/\/www.123fakta.com\/facts-about-probiotics#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.123fakta.com\/"},{"@type":"ListItem","position":2,"name":"Facts about probiotics"}]},{"@type":"WebSite","@id":"https:\/\/www.123fakta.com\/da\/#website","url":"https:\/\/www.123fakta.com\/da\/","name":"123fakta.com","description":"Hechos divertidos, serios y verdaderos","publisher":{"@id":"https:\/\/www.123fakta.com\/da\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.123fakta.com\/da\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.123fakta.com\/da\/#organization","name":"123fakta.com","url":"https:\/\/www.123fakta.com\/da\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.123fakta.com\/da\/#\/schema\/logo\/image\/","url":"https:\/\/www.123fakta.com\/wp-content\/uploads\/logo-123fakta-com.webp","contentUrl":"https:\/\/www.123fakta.com\/wp-content\/uploads\/logo-123fakta-com.webp","width":300,"height":53,"caption":"123fakta.com"},"image":{"@id":"https:\/\/www.123fakta.com\/da\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.123fakta.com\/da\/#\/schema\/person\/8184fc25e34a98422f1bca2a8a55acf2","name":"El Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","caption":"The Editor"},"sameAs":["https:\/\/www.123fakta.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/posts\/4962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/comments?post=4962"}],"version-history":[{"count":0,"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/posts\/4962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/media\/7552"}],"wp:attachment":[{"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/media?parent=4962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/categories?post=4962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.123fakta.com\/es\/wp-json\/wp\/v2\/tags?post=4962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}